{"id":3400,"date":"2024-07-31T11:04:19","date_gmt":"2024-07-31T09:04:19","guid":{"rendered":"http:\/\/fyqorne.cluster023.hosting.ovh.net\/politica-de-cookies-ue\/"},"modified":"2024-07-31T11:09:28","modified_gmt":"2024-07-31T09:09:28","slug":"politica-de-cookies-ue","status":"publish","type":"page","link":"https:\/\/danielmarti.es\/cat\/politica-de-cookies-ue\/","title":{"rendered":"Pol\u00edtica de cookies (UE)"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"3400\" class=\"elementor elementor-3400\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5aa14ab1 e-flex e-con-boxed e-con e-parent\" data-id=\"5aa14ab1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-507699a elementor-widget elementor-widget-heading\" data-id=\"507699a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pol\u00edtica de cookies<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3798decf elementor-widget elementor-widget-shortcode\" data-id=\"3798decf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n<!-- Legal document generated by Complianz | GDPR\/CCPA Cookie Consent https:\/\/wordpress.org\/plugins\/complianz-gdpr -->\n<div id=\"cmplz-document\" class=\"cmplz-document cookie-statement cmplz-document-eu\"><p><i>Aquesta pol\u00edtica de galetes es va actualitzar per \u00faltima vegada el 31\/07\/2024 i s\u2019aplica a ciutadans i residents legals permanents de l'Espai Econ\u00f2mic Europeu i Su\u00efssa.<\/i><br><\/p><h2>1. Introducci\u00f3<\/h2><p>El nostre lloc web, <a href=\"https:\/\/danielmarti.es\/cat\">https:\/\/danielmarti.es\/cat<\/a> (d'ara endavant  \"el lloc web\") utilitza galetes i altres tecnologies relacionades (per comoditat, totes les tecnologies es denominen  \"galetes\"). Les galetes tamb\u00e9 s\u00f3n col\u00b7locades per tercers que hem contractat. En el document seg\u00fcent us informem sobre l'\u00fas de les galetes al nostre lloc web.<\/p><h2>2. Qu\u00e8 s\u00f3n les galetes?<\/h2><p>Una galeta \u00e9s un fitxer petit i senzill que s'envia juntament amb p\u00e0gines d'aquest lloc web i que el vostre navegador emmagatzema al disc dur de l'ordinador o un altre dispositiu. La informaci\u00f3 emmagatzemada en ell es pot tornar als nostres servidors o als servidors dels tercers corresponents durant una visita posterior.<\/p><h2>3. Qu\u00e8 s\u00f3n els scripts?<\/h2><p>Un script \u00e9s una pe\u00e7a de codi de programari que s'utilitza per a que el nostre web funcioni correctament i interactivament. Aquest codi s'executa al nostre servidor o al vostre dispositiu.<\/p><h2>4. Qu\u00e8 \u00e9s una balisa web?<\/h2><p>Una balisa web (o una etiqueta de p\u00edxel) \u00e9s una petita i invisible pe\u00e7a de text o imatge en un lloc web que s'utilitza per controlar el tr\u00e0nsit d'un lloc web. Per fer-ho, s'emmagatzemen diverses dades utilitzant balises web.<\/p><h2>5. Galetes<\/h2><p class=\"cmplz-subtitle\">5.1 Galetes t\u00e8cniques o funcionals<\/p><p>Algunes galetes asseguren que certes parts del lloc web funcionen correctament i que les prefer\u00e8ncies dels usuaris segueixin sent conegudes. Utilitzant galetes funcionals, us facilitem que visiteu el nostre lloc web. D'aquesta manera, no cal que introdu\u00efu repetidament la mateixa informaci\u00f3 quan visiteu el nostre lloc web i, per exemple, els elements romanen al carret\u00f3 de la compra fins que h\u00e0giu pagat. Podem posar aquestes galetes sense el vostre consentiment.<\/p><p class=\"cmplz-subtitle\">5.2 Cookies d&#039;estad\u00edstica<\/p><p>Utilitzem cookies anal\u00edtiques per optimitzar l'experi\u00e8ncia del lloc web per als nostres usuaris. Amb aquestes cookies anal\u00edtiques obtenim informaci\u00f3 sobre l'\u00fas del nostre lloc web.&nbsp;Us demanem perm\u00eds per col\u00b7locar cookies d'estad\u00edstiques.<\/p><p class=\"cmplz-subtitle\">5.3 Cookies de m\u00e0rqueting\/seguiment<\/p><p>Les galetes de m\u00e0rqueting\/seguiment s\u00f3n galetes o qualsevol altra forma d'emmagatzematge local que s'utilitzen per crear perfils d'usuari per mostrar publicitat o per fer un seguiment de l'usuari en aquest lloc web o en diversos llocs web amb finalitats de m\u00e0rqueting similars.<\/p><h2>6. Galetes col\u00b7locades<\/h2><div id=\"cmplz-cookies-overview\"><details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Elementor<\/h3>\n\t\t<p>Finalitat pendent d'investigaci\u00f3<\/p>\n\t\t<label for=\"cmplz_service_elementor\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service elementor<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_elementor\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"elementor\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>\u00das<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartint dades<\/h4>\n\t\t<p>Aquestes dades no es comparteixen amb tercers.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Finalitat pendent d'investigaci\u00f3<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/elementor\/\">elementor<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WordPress<\/h3>\n\t\t<p>Finalitat pendent d'investigaci\u00f3<\/p>\n\t\t<label for=\"cmplz_service_wordpress\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service wordpress<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wordpress\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wordpress\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>\u00das<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartint dades<\/h4>\n\t\t<p>Aquestes dades no es comparteixen amb tercers.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Finalitat pendent d'investigaci\u00f3<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/wpemojisettingssupports\/\">wpEmojiSettingsSupports<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/wp-settings-time\/\">wp-settings-time-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/wordpress_test_cookie\/\">wordpress_test_cookie<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/wordpress_logged_in_\/\">wordpress_logged_in_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/wp-settings\/\">wp-settings-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/wp_preferences_user_\/\">WP_PREFERENCES_USER_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Fonts<\/h3>\n\t\t<p>Finalitat pendent d'investigaci\u00f3<\/p>\n\t\t<label for=\"cmplz_service_google-fonts\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-fonts<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-fonts\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-fonts\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>\u00das<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartint dades<\/h4>\n\t\t<p>Aquestes dades no es comparteixen amb tercers.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Finalitat pendent d'investigaci\u00f3<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">Google Fonts API<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google reCAPTCHA<\/h3>\n\t\t<p>Finalitat pendent d'investigaci\u00f3<\/p>\n\t\t<label for=\"cmplz_service_google-recaptcha\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-recaptcha<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-recaptcha\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-recaptcha\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>\u00das<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartint dades<\/h4>\n\t\t<p>Aquestes dades no es comparteixen amb tercers.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Finalitat pendent d'investigaci\u00f3<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">rc::c<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">rc::b<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">rc::a<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Maps<\/h3>\n\t\t<p>Finalitat pendent d'investigaci\u00f3<\/p>\n\t\t<label for=\"cmplz_service_google-maps\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-maps<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-maps\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-maps\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>\u00das<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartint dades<\/h4>\n\t\t<p>Aquestes dades no es comparteixen amb tercers.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Finalitat pendent d'investigaci\u00f3<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">Google Maps API<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Diversos<\/h3>\n\t\t<p>Finalitat pendent d'investigaci\u00f3<\/p>\n\t\t<label for=\"cmplz_service_diversos\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service diversos<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_diversos\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"diversos\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>\u00das<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartint dades<\/h4>\n\t\t<p>L'intercanvi de dades est\u00e0 pendent d'investigaci\u00f3<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Finalitat pendent d'investigaci\u00f3<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">e_globals<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">e_kit-elements-defaults<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">_ga<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_banner-status<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">365 dies<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">_ga_83ZZBF9MLH<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_functional<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">365 dies<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_statistics<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">365 dies<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_preferences<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">365 dies<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_marketing<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">365 dies<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">tt_helper_installed<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wp_lang<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_consented_services<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">365 dies<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_policy_id<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">365 dies<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">acf<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">mp_150605b3b9f979922f2ac5a52e2dcfe9_mixpanel<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">mp_gen_new_tab_id_mixpanel_150605b3b9f979922f2ac5a52e2dcfe9<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">mp_tab_id_mixpanel_150605b3b9f979922f2ac5a52e2dcfe9<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<\/div><h2>7. Consentiment<\/h2><p>Quan visiteu el nostre lloc web per primera vegada, us mostrarem un missatge emergent amb una explicaci\u00f3 sobre les cookies. Tan bon punt com feu clic a \"Guardar preferencias\", ens consentiu a utilitzar les categories de cookies i extensions que heu seleccionat al missatge emergent, tal i com es descriu en aquesta Pol\u00edtica de cookies. Podeu desactivar l\u2019\u00fas de cookies a trav\u00e9s del vostre navegador, per\u00f2 tingueu en compte que pot ser que el nostre lloc web ja no funcioni correctament.<\/p><p class=\"cmplz-subtitle\">7.1 Gestioneu la vostra configuraci\u00f3 de consentiment<\/p><div id=\"cmplz-manage-consent-container-nojavascript\">Heu carregat la Pol\u00edtica de galetes sense suport javascript.&nbsp;A AMP, podeu utilitzar el bot\u00f3 de gesti\u00f3 del consentiment a la part inferior de la p\u00e0gina.<\/div><div id=\"cmplz-manage-consent-container\" class=\"cmplz-manage-consent-container\"><\/div><h2>8. Activaci\u00f3 \/ desactivaci\u00f3 i eliminaci\u00f3 de galetes<\/h2><p>Podeu utilitzar el navegador per a esborrar les cookies autom\u00e0ticament o manualment. A m\u00e9s, podeu especificar que determinades cookies no siguin col\u00b7locades. Una altra opci\u00f3 \u00e9s canviar les prefer\u00e8ncies del vostre navegador per a rebre un missatge cada cop que una cookie \u00e9s col\u00b7locada. Per a m\u00e9s informaci\u00f3, podeu consultar les instruccions a l'Ajuda del vostre navegador.<\/p><p>Tingueu en compte que el nostre lloc web pot no funcionar correctament si totes les galetes estan desactivades. Si suprimiu les galetes del navegador, se'n crearan de noves despr\u00e9s del vostre consentiment quan torneu a visitar els nostres llocs web.<\/p><h2>9. Els vostres drets respecte de les dades personals<\/h2><p>Teniu els drets seg\u00fcents respecte a les vostres dades personals:<\/p><ul>\n                    <li>Teniu dret a saber per qu\u00e8 es necessiten les vostres dades personals, qu\u00e8 hi passar\u00e0 i quant de temps es conservaran.<\/li>\n                    <li>Dret d'acc\u00e9s: teniu dret a accedir a les vostres dades personals que ens s\u00f3n conegudes.<\/li>\n                    <li>Dret de rectificaci\u00f3: teniu dret a completar, corregir, suprimir o bloquejar les vostres dades personals sempre que ho desitgeu.<\/li>\n                    <li>Si ens doneu el consentiment per processar les seves dades, teniu el dret de revocar aquest consentiment i de suprimir les vostres dades personals.<\/li>\n                    <li>Dret de transferir les vostres dades: teniu el dret de sol\u00b7licitar totes les dades personals del controlador i transferir-les en la seva totalitat a un altre controlador.<\/li>\n                    <li>Dret a l'oposici\u00f3: podeu oposar-vos al processament de les vostres dades. Complim amb aix\u00f2, tret que hi hagi motius justificats per al processament.<\/li>\n                <\/ul><p>Per exercir aquests drets, poseu-vos en contacte amb nosaltres. Consulteu les dades de contacte a la part inferior d'aquesta Pol\u00edtica de cookies. Si teniu una queixa sobre com gestionem les vostres dades, ens agradaria escoltar-vos, per\u00f2 tamb\u00e9 teniu el dret de presentar una reclamaci\u00f3 a l'autoritat de supervisi\u00f3 (l'Ag\u00e8ncia de Protecci\u00f3 de Dades).<\/p><h2>10. Detalls de contacte<\/h2><p>Per a preguntes i\/o comentaris sobre la nostra Pol\u00edtica de galetes i aquesta declaraci\u00f3, poseu-vos en contacte amb nosaltres mitjan\u00e7ant les seg\u00fcents dades de contacte:<\/p><p><span class=\"cmplz-contact-organisation\">Daniel Josep Mart\u00ed i P\u00e9rez<\/span><br>\n                      <span class=\"cmplz-contact-address\">Calle Alcoi 50, 1, Onil, 03430, Alicante<\/span><br>\n                      <span class=\"cmplz-contact-country\">Espanya<\/span><br>\n                    Lloc web: <span class=\"cmplz-contact-domain\"><a href=\"https:\/\/danielmarti.es\/cat\">https:\/\/danielmarti.es\/cat<\/a><\/span><br>\n                    Correu electr\u00f2nic: <span class=\"cmplz-contact-email\"><span class=\"cmplz-obfuscate\">dm&#112;@<span class=\"cmplz-fmail-domain\">&#101;x.c&#111;m<\/span>d&#097;nie&#108;&#109;&#097;r&#116;i&#046;&#101;s<\/span><\/span><br>\n                    <span class=\"cmplz-contact-telephone\">Phone number: 965 565 268<\/span><\/p><p>Aquesta pol\u00edtica de galetes s'ha sincronitzat amb <a href=\"https:\/\/cookiedatabase.org\/\" target=\"_blank\">cookiedatabase.org<\/a> el 20\/09\/2024.<\/p><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88d7706 elementor-widget elementor-widget-html\" data-id=\"88d7706\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>\n    .elementor-shortcode {\n    display: flex;\n    justify-content: center;\n    }\n    \n   .cmplz-document p {\n      font-family: \"Ubuntu\";\n   font-size: 20 px;\n   font-weight: 300;\n    }\n    \n      .cmplz-document li {\n      font-family: \"Ubuntu\";\n   font-size: 20 px;\n   font-weight: 500;\n    }\n    \n     .cmplz-document h2 {\n      font-family: \"Ubuntu\";\n   font-size: 51 px;\n   font-weight: 500;\n    }\n    \n    .cmplz-document h3 {\n      font-family: \"Ubuntu\";\n   font-size: 51 px;\n   font-weight: 500;\n    }\n    \n   #cmplz-document, .editor-styles-wrapper .cmplz-unlinked-mode {\n       max-width: 1200px;\n   }\n    \n<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Pol\u00edtica de cookies<\/p>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3400","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pol\u00edtica de cookies (UE) - DMP<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de cookies (UE) - DMP\" \/>\n<meta property=\"og:description\" content=\"Pol\u00edtica de cookies\" \/>\n<meta property=\"og:url\" content=\"https:\/\/danielmarti.es\/cat\/politica-de-cookies-ue\/\" \/>\n<meta property=\"og:site_name\" content=\"DMP\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-31T09:09:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/danielmarti.es\/wp-content\/uploads\/2024\/07\/dmp-logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"513\" \/>\n\t<meta property=\"og:image:height\" content=\"513\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/danielmarti.es\/politica-de-cookies-ue\/\",\"url\":\"https:\/\/danielmarti.es\/politica-de-cookies-ue\/\",\"name\":\"Pol\u00edtica de cookies (UE) - DMP\",\"isPartOf\":{\"@id\":\"https:\/\/fyqorne.cluster023.hosting.ovh.net\/#website\"},\"datePublished\":\"2024-07-31T09:04:19+00:00\",\"dateModified\":\"2024-07-31T09:09:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/danielmarti.es\/politica-de-cookies-ue\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/danielmarti.es\/politica-de-cookies-ue\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/danielmarti.es\/politica-de-cookies-ue\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/danielmarti.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de cookies (UE)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fyqorne.cluster023.hosting.ovh.net\/#website\",\"url\":\"https:\/\/fyqorne.cluster023.hosting.ovh.net\/\",\"name\":\"DMP\",\"description\":\"Daniel Mart\u00ed - Arquitectura\",\"publisher\":{\"@id\":\"https:\/\/fyqorne.cluster023.hosting.ovh.net\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fyqorne.cluster023.hosting.ovh.net\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/fyqorne.cluster023.hosting.ovh.net\/#organization\",\"name\":\"Daniel Mart\u00ed - Arquitectura\",\"alternateName\":\"DMP\",\"url\":\"https:\/\/fyqorne.cluster023.hosting.ovh.net\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/fyqorne.cluster023.hosting.ovh.net\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/fyqorne.cluster023.hosting.ovh.net\/wp-content\/uploads\/2024\/07\/cropped-dmp-logo.png\",\"contentUrl\":\"http:\/\/fyqorne.cluster023.hosting.ovh.net\/wp-content\/uploads\/2024\/07\/cropped-dmp-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Daniel Mart\u00ed - Arquitectura\"},\"image\":{\"@id\":\"https:\/\/fyqorne.cluster023.hosting.ovh.net\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de cookies (UE) - DMP","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"ca_ES","og_type":"article","og_title":"Pol\u00edtica de cookies (UE) - DMP","og_description":"Pol\u00edtica de cookies","og_url":"https:\/\/danielmarti.es\/cat\/politica-de-cookies-ue\/","og_site_name":"DMP","article_modified_time":"2024-07-31T09:09:28+00:00","og_image":[{"width":513,"height":513,"url":"https:\/\/danielmarti.es\/wp-content\/uploads\/2024\/07\/dmp-logo.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/danielmarti.es\/politica-de-cookies-ue\/","url":"https:\/\/danielmarti.es\/politica-de-cookies-ue\/","name":"Pol\u00edtica de cookies (UE) - DMP","isPartOf":{"@id":"https:\/\/fyqorne.cluster023.hosting.ovh.net\/#website"},"datePublished":"2024-07-31T09:04:19+00:00","dateModified":"2024-07-31T09:09:28+00:00","breadcrumb":{"@id":"https:\/\/danielmarti.es\/politica-de-cookies-ue\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/danielmarti.es\/politica-de-cookies-ue\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/danielmarti.es\/politica-de-cookies-ue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/danielmarti.es\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de cookies (UE)"}]},{"@type":"WebSite","@id":"https:\/\/fyqorne.cluster023.hosting.ovh.net\/#website","url":"https:\/\/fyqorne.cluster023.hosting.ovh.net\/","name":"DMP","description":"Daniel Mart\u00ed - Arquitectura","publisher":{"@id":"https:\/\/fyqorne.cluster023.hosting.ovh.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fyqorne.cluster023.hosting.ovh.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/fyqorne.cluster023.hosting.ovh.net\/#organization","name":"Daniel Mart\u00ed - Arquitectura","alternateName":"DMP","url":"https:\/\/fyqorne.cluster023.hosting.ovh.net\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/fyqorne.cluster023.hosting.ovh.net\/#\/schema\/logo\/image\/","url":"http:\/\/fyqorne.cluster023.hosting.ovh.net\/wp-content\/uploads\/2024\/07\/cropped-dmp-logo.png","contentUrl":"http:\/\/fyqorne.cluster023.hosting.ovh.net\/wp-content\/uploads\/2024\/07\/cropped-dmp-logo.png","width":512,"height":512,"caption":"Daniel Mart\u00ed - Arquitectura"},"image":{"@id":"https:\/\/fyqorne.cluster023.hosting.ovh.net\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/danielmarti.es\/cat\/wp-json\/wp\/v2\/pages\/3400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/danielmarti.es\/cat\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/danielmarti.es\/cat\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/danielmarti.es\/cat\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/danielmarti.es\/cat\/wp-json\/wp\/v2\/comments?post=3400"}],"version-history":[{"count":7,"href":"https:\/\/danielmarti.es\/cat\/wp-json\/wp\/v2\/pages\/3400\/revisions"}],"predecessor-version":[{"id":3408,"href":"https:\/\/danielmarti.es\/cat\/wp-json\/wp\/v2\/pages\/3400\/revisions\/3408"}],"wp:attachment":[{"href":"https:\/\/danielmarti.es\/cat\/wp-json\/wp\/v2\/media?parent=3400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}